{"id":6073,"date":"2025-02-12T16:37:27","date_gmt":"2025-02-12T19:37:27","guid":{"rendered":"https:\/\/gustavoadolfo.com.br\/saocristovao\/?p=6073"},"modified":"2025-02-12T16:40:53","modified_gmt":"2025-02-12T19:40:53","slug":"elementor-6073","status":"publish","type":"post","link":"https:\/\/gustavoadolfo.com.br\/saocristovao\/2025\/02\/12\/elementor-6073\/","title":{"rendered":"Professores e funcion\u00e1rios do GA participam de imers\u00e3o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6073\" class=\"elementor elementor-6073\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87d23ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87d23ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2acc9a\" data-id=\"a2acc9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54c3dce elementor-widget elementor-widget-text-editor\" data-id=\"54c3dce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Professores e funcion\u00e1rios do Centro de Educa\u00e7\u00e3o B\u00e1sica Gustavo Adolfo participaram de uma imers\u00e3o entre segunda (10) e ter\u00e7a-feira (11), em S\u00e3o Leopoldo. O Centro de Espiritualidade Cristo Rei (Cecrei) recebeu os quase 130 profissionais nos dois dias de atividades.<br \/>Com a tem\u00e1tica &#8220;A\u00e7\u00f5es que transformam: Fortalecendo o Compromisso, os Princ\u00edpios e o Protagonismo no GA&#8221;, a forma\u00e7\u00e3o prepara a equipe para o mais um ano letivo que tem in\u00edcio na segunda-feira (17), nas duas unidades.<br \/>Al\u00e9m da integra\u00e7\u00e3o da equipe e da an\u00e1lise e discuss\u00e3o de projetos para 2025, os colaboradores assistiram ao concerto do Grupo Sonata Musical e conheceram a sede da Rede Sinodal de Educa\u00e7\u00e3o, da Editora Sinodal, da Faculdade EST e da ISAEC &#8211; mantenedora do GA.<\/p><p>Ano letivo<br \/>Na segunda (17), o Col\u00e9gio Sinodal Gustavo Adolfo, localizado no bairro S\u00e3o Crist\u00f3v\u00e3o, recebe os estudantes da Educa\u00e7\u00e3o Infantil at\u00e9 o 8\u00ba ano do Ensino Fundamental. J\u00e1 os estudantes de 9\u00ba ano do Ensino Fundamental at\u00e9 o Ensino M\u00e9dio s\u00e3o acolhidos na Unidade de Ensino M\u00e9dio Gustavo Adolfo Campus Univates.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ff158d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ff158d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf5264e\" data-id=\"bf5264e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1531026 elementor-widget elementor-widget-image\" data-id=\"1531026\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"595\" src=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2025\/02\/IMG_9939-1024x595.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2025\/02\/IMG_9939-1024x595.jpg 1024w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2025\/02\/IMG_9939-300x174.jpg 300w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2025\/02\/IMG_9939-768x446.jpg 768w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2025\/02\/IMG_9939-1536x892.jpg 1536w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2025\/02\/IMG_9939.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Professores e funcion\u00e1rios do Centro de Educa\u00e7\u00e3o B\u00e1sica Gustavo Adolfo participaram de uma imers\u00e3o entre segunda (10) e ter\u00e7a-feira (11), em S\u00e3o Leopoldo. O Centro de Espiritualidade Cristo Rei (Cecrei) recebeu os quase 130 profissionais nos dois dias de atividades. Com a tem\u00e1tica &#8220;A\u00e7\u00f5es que transformam: Fortalecendo o Compromisso, os Princ\u00edpios e o Protagonismo no<br \/><a class=\"moretag\" href=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/2025\/02\/12\/elementor-6073\/\">+ Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/6073"}],"collection":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/comments?post=6073"}],"version-history":[{"count":5,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/6073\/revisions"}],"predecessor-version":[{"id":6079,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/6073\/revisions\/6079"}],"wp:attachment":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media?parent=6073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/categories?post=6073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/tags?post=6073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}