{"id":5541,"date":"2023-03-10T10:28:37","date_gmt":"2023-03-10T13:28:37","guid":{"rendered":"https:\/\/gustavoadolfo.com.br\/saocristovao\/?p=5541"},"modified":"2023-03-10T10:28:39","modified_gmt":"2023-03-10T13:28:39","slug":"patinadoras-do-ga-sao-convocadas-para-representar-a-selecao-brasileira-em-competicao-no-paraguai","status":"publish","type":"post","link":"https:\/\/gustavoadolfo.com.br\/saocristovao\/2023\/03\/10\/patinadoras-do-ga-sao-convocadas-para-representar-a-selecao-brasileira-em-competicao-no-paraguai\/","title":{"rendered":"Patinadoras do GA s\u00e3o convocadas para representar a Sele\u00e7\u00e3o Brasileira em competi\u00e7\u00e3o no Paraguai"},"content":{"rendered":"\n<p>A estudante do 8\u00ba ano do GA, Sofia B\u00fcndrich Garcia, e a ex-aluna Stela B\u00fcndrich Garcia foram convocadas para a Sele\u00e7\u00e3o Brasileira nos Jogos Sulamericanos de Esportes Sobre Rodas que acontecer\u00e3o em abril, no Paraguai.<\/p>\n\n\n\n<p>A convoca\u00e7\u00e3o se deve aos resultados alcan\u00e7adas no final de fevereiro, no Campeonato Brasileiro de Patina\u00e7\u00e3o Art\u00edstica 2023, que ocorreu em Bras\u00edlia. Em tr\u00eas provas, as atletas tiveram classifica\u00e7\u00e3o que as leva \u00e0 competi\u00e7\u00e3o. Veja os resultados:<\/p>\n\n\n\n<p>Sofia:<\/p>\n\n\n\n<p>1\u00ba lugar &#8211; Grupo de Precis\u00e3o Junior Internacional<\/p>\n\n\n\n<p>Stela:<\/p>\n\n\n\n<p>2\u00ba lugar &#8211; Quarteto S\u00eanior Internacional<\/p>\n\n\n\n<p>3\u00ba lugar &#8211; Livre Junior Internacional<\/p>\n\n\n\n<p>Elas fazem parte da Academia de Patina\u00e7\u00e3o Arte e Movimento e s\u00e3o acompanhadas pelas t\u00e9cnicas Gabriela e Ge\u00f3rgia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"715\" height=\"1024\" src=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2023\/03\/Stela-e-Sofia-convocadas.jpeg\" alt=\"\" class=\"wp-image-5542\" srcset=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2023\/03\/Stela-e-Sofia-convocadas.jpeg 715w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2023\/03\/Stela-e-Sofia-convocadas-209x300.jpeg 209w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A estudante do 8\u00ba ano do GA, Sofia B\u00fcndrich Garcia, e a ex-aluna Stela B\u00fcndrich Garcia foram convocadas para a Sele\u00e7\u00e3o Brasileira nos Jogos Sulamericanos de Esportes Sobre Rodas que acontecer\u00e3o em abril, no Paraguai. A convoca\u00e7\u00e3o se deve aos resultados alcan\u00e7adas no final de fevereiro, no Campeonato Brasileiro de Patina\u00e7\u00e3o Art\u00edstica 2023, que ocorreu<br \/><a class=\"moretag\" href=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/2023\/03\/10\/patinadoras-do-ga-sao-convocadas-para-representar-a-selecao-brasileira-em-competicao-no-paraguai\/\">+ Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/5541"}],"collection":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/comments?post=5541"}],"version-history":[{"count":1,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/5541\/revisions"}],"predecessor-version":[{"id":5543,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/5541\/revisions\/5543"}],"wp:attachment":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media?parent=5541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/categories?post=5541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/tags?post=5541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}