{"id":500,"date":"2018-12-04T11:12:21","date_gmt":"2018-12-04T13:12:21","guid":{"rendered":"http:\/\/gustavoadolfo.com.br\/portal\/?p=500"},"modified":"2018-12-04T11:12:21","modified_gmt":"2018-12-04T13:12:21","slug":"estudante-do-colegio-sinodal-gustavo-adolfo-e-destaque-na-matematica-a-nivel-estadual","status":"publish","type":"post","link":"https:\/\/gustavoadolfo.com.br\/saocristovao\/2018\/12\/04\/estudante-do-colegio-sinodal-gustavo-adolfo-e-destaque-na-matematica-a-nivel-estadual\/","title":{"rendered":"Estudante do Col\u00e9gio Sinodal Gustavo Adolfo \u00e9 destaque na Matem\u00e1tica a n\u00edvel Estadual"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-501\" src=\"http:\/\/gustavoadolfo.com.br\/portal\/wp-content\/uploads\/2018\/12\/OBMEP_Carlos-Eduardo-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2018\/12\/OBMEP_Carlos-Eduardo-300x200.jpg 300w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2018\/12\/OBMEP_Carlos-Eduardo-768x512.jpg 768w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2018\/12\/OBMEP_Carlos-Eduardo-1024x683.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"font-weight: 400;\"><em>Carlos Eduardo Stahlh\u00f6fer, do 7\u00ba ano, obteve melhor nota do RS em sua categoria.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">O\u00a0estudante do 7\u00ba ano do Col\u00e9gio Sinodal Gustavo Adolfo (CSGA), Carlos Eduardo Stahlh\u00f6fer, \u00e9 destaque na Ol\u00edmpiada Brasileira de Matem\u00e1tica das Escolas P\u00fablicas (OBMEP 2018 \u2013 Escolas P\u00fablicas + Privadas). Carlos Eduardo estuda na institui\u00e7\u00e3o desde o 2\u00ba ano do Ensino Fundamental e conquistou uma das Medalhas de Prata no n\u00edvel 1 (6\u00ba ou 7\u00ba ano do Ensino Fundamental)\u00a0da OBMEP.<\/p>\n<p style=\"font-weight: 400;\">A n\u00edvel estadual, Carlos Eduardo obteve a 1\u00aa posi\u00e7\u00e3o e a n\u00edvel nacional o 52\u00ba lugar. Em fun\u00e7\u00e3o do seu \u00f3timo desempenho foi convidado a participar do 14\u00ba Programa de Inicia\u00e7\u00e3o Cient\u00edfica Jr. (PIC) no pr\u00f3ximo ano.<\/p>\n<p style=\"font-weight: 400;\">As provas foram realizadas em 5 de junho (1\u00aa fase) e 15 de setembro (2\u00aa fase), envolvendo cerca de 18 milh\u00f5es de estudantes no Brasil. Foram classificados 20 estudantes do Gustavo Adolfo para a segunda fase de testes. Trata-se da mais importante competi\u00e7\u00e3o cient\u00edfica brasileira em 2018.<\/p>\n<p style=\"font-weight: 400;\">Al\u00e9m do estudante Carlos Eduardo, outros seis alunos do CSGA foram contemplados com Men\u00e7\u00e3o Honrosa: Arthur Brust Schwingel (7\u00ba ano), Gabriela Fernandes Noll (7\u00ba ano), Ana Carolina Baller R\u00f6hsig (9\u00ba ano), Thiago Krilow (9\u00ba ano), Vin\u00edcius Navarro Serique de Sousa (2\u00ba ano \u2013 Ensino M\u00e9dio) e Nicole Elisa Lansing (3\u00ba ano \u2013 Ensino M\u00e9dio).<\/p>\n<p style=\"font-weight: 400;\">A coordenadora da \u00e1rea da Matem\u00e1tica Rosilene In\u00eas K\u00f6nig enfatiza que \u201cS\u00e3o resultados do nosso projeto de educa\u00e7\u00e3o. A partir da reestrutura\u00e7\u00e3o da equipe de coordena\u00e7\u00e3o em \u00e1reas do conhecimento (Matem\u00e1tica, Linguagens, Ci\u00eancias Humanas e da Natureza), buscamos fomentar ainda mais a aprendizagem em cada uma das \u00e1reas, beneficiando assim professores e estudantes. Os professores que auxiliaram est\u00e3o muito orgulhosos da conquista, principalmente a professora Neusa, da disciplina de matem\u00e1tica!\u201d, comenta.<\/p>\n<p style=\"font-weight: 400;\">O diretor do Col\u00e9gio Sinodal Gustavo Adolfo, Edson Wieth\u00f6lter, destaca as pr\u00e1ticas pedag\u00f3gicas do educand\u00e1rio como incentivadoras da busca pela excel\u00eancia. \u201cO col\u00e9gio perpetua princ\u00edpios fundamentados na valoriza\u00e7\u00e3o das artes, das l\u00ednguas, conte\u00fado forte de aprendizagem significativa e com excelentes professores\u201d, completa.<\/p>\n<p style=\"font-weight: 400;\"><strong>Sobre a OBMEP<\/strong><\/p>\n<p style=\"font-weight: 400;\">A Olimp\u00edada Brasileira de Matem\u00e1tica das Escolas P\u00fablicas (OBMEP) \u00e9 um projeto a n\u00edvel nacional voltado \u00e0s escolas p\u00fablicas e privadas. \u00c9 realizada pelo Instituto Nacional de Matem\u00e1tica Pura e Aplicada (IMPA), com apoio da Sociedade Brasileira de Matem\u00e1tica (SBM). A olimp\u00edada \u00e9 direcionada aos alunos do 6\u00ba ano do Ensino Fundamental at\u00e9 o \u00faltimo ano do Ensino M\u00e9dio, de escolas p\u00fablicas e privadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlos Eduardo Stahlh\u00f6fer, do 7\u00ba ano, obteve melhor nota do RS em sua categoria. &nbsp; O\u00a0estudante do 7\u00ba ano do Col\u00e9gio Sinodal Gustavo Adolfo (CSGA), Carlos Eduardo Stahlh\u00f6fer, \u00e9 destaque na Ol\u00edmpiada Brasileira de Matem\u00e1tica das Escolas P\u00fablicas (OBMEP 2018 \u2013 Escolas P\u00fablicas + Privadas). Carlos Eduardo estuda na institui\u00e7\u00e3o desde o 2\u00ba ano do<br \/><a class=\"moretag\" href=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/2018\/12\/04\/estudante-do-colegio-sinodal-gustavo-adolfo-e-destaque-na-matematica-a-nivel-estadual\/\">+ Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":501,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/500"}],"collection":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/comments?post=500"}],"version-history":[{"count":1,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/500\/revisions"}],"predecessor-version":[{"id":502,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/500\/revisions\/502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media\/501"}],"wp:attachment":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media?parent=500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/categories?post=500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/tags?post=500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}