{"id":1435,"date":"2021-09-01T09:00:07","date_gmt":"2021-09-01T12:00:07","guid":{"rendered":"https:\/\/gustavoadolfo.com.br\/portal\/?p=1435"},"modified":"2021-08-31T17:25:23","modified_gmt":"2021-08-31T20:25:23","slug":"gustavo-adolfo-tera-parceria-com-a-univates-no-ensino-medio-e-turmas-bilingues-a-partir-de-2022","status":"publish","type":"post","link":"https:\/\/gustavoadolfo.com.br\/saocristovao\/2021\/09\/01\/gustavo-adolfo-tera-parceria-com-a-univates-no-ensino-medio-e-turmas-bilingues-a-partir-de-2022\/","title":{"rendered":"Gustavo Adolfo ter\u00e1 parceria com a Univates no Ensino M\u00e9dio e turmas bil\u00edngues a partir de 2022"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O Col\u00e9gio Sinodal Gustavo Adolfo lan\u00e7a, na manh\u00e3 desta quarta-feira (01), dois projetos in\u00e9ditos na regi\u00e3o &#8211; um deles em parceria com a Universidade do Vale do Taquari (Univates). Autoridades, estudantes de 9\u00ba ano e imprensa prestigiam a apresenta\u00e7\u00e3o das novidades no Teatro Univates. O p\u00fablico em geral acompanha as explana\u00e7\u00f5es pelos canais digitais das institui\u00e7\u00f5es. A Orquestra Gustavo Adolfo \/ Univates participa do evento.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Um dos programas a ser lan\u00e7ado \u00e9 o Projeto Bil\u00edngue que vai vigorar a partir do ano que vem no GA. A proposta \u00e9 de dois professores simult\u00e2neos, em Portugu\u00eas e Ingl\u00eas, para estudantes que ingressarem no N\u00edvel III da Educa\u00e7\u00e3o Infantil e no 1\u00ba ano do Ensino Fundamental. Os estudantes ter\u00e3o contato com as duas l\u00ednguas desde cedo e de forma integral, incentivando o desenvolvimento do segundo idioma com naturalidade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O Novo Ensino M\u00e9dio Gustavo Adolfo campus Univates tamb\u00e9m ser\u00e1 apresentado oficialmente nesta manh\u00e3. Ele vai al\u00e9m de uma adequa\u00e7\u00e3o \u00e0 legisla\u00e7\u00e3o federal. A proposta \u00e9 de um Ensino M\u00e9dio baseado nas necessidades da regi\u00e3o, a partir de pesquisas de dois anos desenvolvidas pela expertise de mais de meio s\u00e9culo do GA e usando as estruturas da Univates. Um dos destaques a partir da parceria \u00e9 que os estudantes participar\u00e3o de disciplinas eletivas de cursos t\u00e9cnicos (1\u00ba e 2\u00ba anos) e de gradua\u00e7\u00e3o (3\u00ba ano) da institui\u00e7\u00e3o.<\/span><\/p>\n<h2><b>Saiba mais sobre o Novo Ensino M\u00e9dio<\/b><\/h2>\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-1423\" src=\"https:\/\/gustavoadolfo.com.br\/portal\/wp-content\/uploads\/2021\/08\/IMG_5115-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/08\/IMG_5115-300x225.jpg 300w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/08\/IMG_5115-768x577.jpg 768w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/08\/IMG_5115-1024x769.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Nova estrutura e mais autonomia aguardam os estudantes que ingressarem no Ensino M\u00e9dio em 2022 na Unidade de Ensino M\u00e9dio Gustavo Adolfo &#8211; campus Univates. No pr\u00e9dio 1 da universidade, os discentes poder\u00e3o usufruir de uma proposta de ensino, baseada no desenvolvimento de m\u00faltiplas habilidades, que constitui o Novo Ensino M\u00e9dio &#8211; Gustavo Adolfo campus Univates.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cTeremos autonomia e oportunidade de escolhas, em um projeto in\u00e9dito que tem como princ\u00edpios pedag\u00f3gicos a experimenta\u00e7\u00e3o, a comunica\u00e7\u00e3o, a cria\u00e7\u00e3o, a conex\u00e3o e o conhecimento,\u00a0 al\u00e9m de um diferencial de espa\u00e7os, de cen\u00e1rio, laborat\u00f3rios de alto padr\u00e3o\u201d, comenta o Diretor do GA, Edson Wieth\u00f6lter.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O Gustavo Adolfo j\u00e1 det\u00e9m o maior Ensino M\u00e9dio privado da regi\u00e3o, com 160 estudantes matriculados. A parceria com a Univates amplia a quest\u00e3o estrutural e permite a oferta de novas possibilidades.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Projeto baseado em pesquisa na comunidade<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A comiss\u00e3o idealizadora do projeto do Novo Ensino M\u00e9dio re\u00fane integrantes das duas institui\u00e7\u00f5es. Iniciou os trabalhos h\u00e1 cerca de dois anos. Conforme a comiss\u00e3o, a proposta n\u00e3o \u00e9 simplesmente uma adequa\u00e7\u00e3o \u00e0s Resolu\u00e7\u00f5es n\u00ba 3 e 4\/2018, que atualiza as Diretrizes Nacionais do Novo Ensino M\u00e9dio e que <\/span><span style=\"font-weight: 400;\">institui a Base Nacional Comum Curricular na Etapa do Ensino M\u00e9dio (BNCC-EM), respectivamente<\/span><span style=\"font-weight: 400;\">. O projeto do GA prop\u00f5e ir al\u00e9m das mudan\u00e7as legais, ampliando as possibilidades para os estudantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Uma pesquisa realizada com estudantes, docentes, familiares e lideran\u00e7as regionais apontou dados de expectativas e necessidades que o projeto aborda. \u201cA pesquisa proporcionou uma constru\u00e7\u00e3o coletiva do projeto do Novo Ensino M\u00e9dio e n\u00e3o somente algo proposto por n\u00f3s. Apontou as prioridades na forma\u00e7\u00e3o do estudante no Ensino M\u00e9dio\u201d, comenta a coordenadora de 9\u00ba ano do Ensino Fundamental ao Ensino M\u00e9dio e da \u00e1rea da Matem\u00e1tica, Rosilene K\u00f6nig, integrante da comiss\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A partir da pesquisa realizada com as lideran\u00e7as regionais, por exemplo, p\u00f4de-se conhecer as caracter\u00edsticas esperadas dos profissionais do futuro e as \u00e1reas de forma\u00e7\u00e3o mais promissoras. \u201cAssim obtivemos uma proposta humana e de responsabilidade social\u201d, reitera ela.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O \u2018viver\u2019 e o \u2018conviver\u2019 foram conceitos encontrados na pesquisa, que d\u00e3o for\u00e7a para\u00a0 trabalhar o desenvolvimento de habilidades socioemocionais, de autoconhecimento e de rela\u00e7\u00e3o com o mundo. \u201cOs princ\u00edpios pedag\u00f3gicos, que definimos a partir da an\u00e1lise dos dados das pesquisas, prop\u00f5em que os estudantes tenham suas aulas com din\u00e2micas pensadas nesses aspectos\u201d, explica a coordenadora pedag\u00f3gica da \u00e1rea de Ci\u00eancias Humanas do GA, Mara Forneck.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Como vai funcionar<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O projeto rompe com as disciplinas, e o curr\u00edculo passa a ser por \u00e1reas do conhecimento (Linguagens, Matem\u00e1tica, Ci\u00eancias da Natureza e Ci\u00eancias Humanas e Sociais &#8211; e suas tecnologias). Os estudantes do mesmo ano escolar ter\u00e3o, ao mesmo tempo, as mesmas \u00e1reas, por\u00e9m, com professores de diferentes disciplinas que juntos planejam o conte\u00fado e a din\u00e2mica das aulas. \u201cUm novo jeito de fazer, colocando o estudante no centro do processo, no qual o protagonismo ser\u00e1 o cerne, sem perder alguns focos como Enem e vestibulares\u201d, complementa o diretor Edson Wieth\u00f6lter. Os materiais de apoio ser\u00e3o 100% digitais.<\/span><\/p>\n<p>Al\u00e9m da forma\u00e7\u00e3o geral b\u00e1sica (1.800h), os estudantes ter\u00e3o forma\u00e7\u00f5es espec\u00edficas pautadas nos seguintes pilares:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Viv\u00eancias e experi\u00eancias (1.160h) inclui:<br \/>\n&#8211; Eletivas (280h): participa\u00e7\u00e3o em disciplinas dos cursos t\u00e9cnicos da Univates para estudantes de 1\u00ba e 2\u00ba ano\/EM e em cursos de gradua\u00e7\u00e3o para estudantes do 3\u00ba ano\/EM. S\u00e3o 25 op\u00e7\u00f5es de t\u00e9cnicos\u00a0 e 49 cursos de gradua\u00e7\u00e3o diretamente interligadas \u00e0s \u00e1reas de conhecimento proporcionadas pelas Trilhas;<br \/>\n&#8211; Projeto de vida (240h): constru\u00e7\u00e3o da caminhada, focada em autoconhecimento, com suporte de professor em formato EAD s\u00edncrono;<br \/>\n&#8211; Est\u00fadio (480h): neste componente curricular, os estudantes ser\u00e3o desafiados, em grupos, a desenvolver estudos orientados pelos docentes, envolvendo diferentes projetos;<br \/>\n&#8211; Estudos avan\u00e7ados (160h): exclusivo para o 3\u00ba ano do Ensino M\u00e9dio, para amplia\u00e7\u00e3o de conceitos e habilidades abordando conhecimentos a serem revistos ou aprofundados.<\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Trilhas (640h) &#8211; aprofundamento das \u00e1reas de sa\u00fade (Sanus), engenharias (Faber) e humanidades (Domus). A partir do 2\u00ba ano\/EM, o estudante vivenciar\u00e1 experi\u00eancias nas tr\u00eas Trilhas para que, a partir destas, possa escolher a \u00e1rea de sua prefer\u00eancia para o aprofundamento. Para a defini\u00e7\u00e3o das \u00e1reas de conhecimento, levou-se em considera\u00e7\u00e3o dados da pesquisa realizada com lideran\u00e7as regionais.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Carga hor\u00e1ria<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Atualmente, o Ensino M\u00e9dio no GA conta com 3.300 horas (3.960 per\u00edodos). No Novo Ensino M\u00e9dio, a partir de 2022, a carga hor\u00e1ria passar\u00e1 a ser de 3.600 horas, contemplando a Forma\u00e7\u00e3o Geral B\u00e1sica (1.800) e a Forma\u00e7\u00e3o Espec\u00edfica (1.800h).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O hor\u00e1rio de in\u00edcio e t\u00e9rmino das aulas ser\u00e1 das 7h45min \u00e0s 12h15min, com intervalo de 30 minutos, que sup\u00f5e um espa\u00e7o para conviv\u00eancia, um dos objetivos da proposta de Novo Ensino M\u00e9dio na institui\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outra mudan\u00e7a diz respeito \u00e0 ado\u00e7\u00e3o de semestre, ou seja, o per\u00edodo letivo ser\u00e1 dividido em dois semestres.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Andamento do projeto<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A comiss\u00e3o do Novo Ensino M\u00e9dio trabalha, agora, na defini\u00e7\u00e3o da Arquitetura da Matriz Curricular e na Forma\u00e7\u00e3o dos Docentes que atuar\u00e3o neste novo projeto. \u201cVamos envolver eles ainda mais, pois os docentes s\u00e3o os especialistas no conhecimento\u201d, comenta a coordenadora da \u00e1rea de Linguagens do GA, Deliene Kotz.<\/span><\/p>\n<h2><b>Saiba mais sobre o Projeto Bil\u00edngue<\/b><\/h2>\n<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-1424\" src=\"https:\/\/gustavoadolfo.com.br\/portal\/wp-content\/uploads\/2021\/08\/4_trabalhodocente-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/08\/4_trabalhodocente-300x225.jpg 300w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/08\/4_trabalhodocente-768x577.jpg 768w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/08\/4_trabalhodocente-1024x769.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">O Col\u00e9gio Sinodal Gustavo Adolfo passar\u00e1 a contar com turmas bil\u00edngues a partir de 2022. Estudantes que ingressarem no N\u00edvel III da Educa\u00e7\u00e3o Infantil (5 anos) e no 1\u00ba ano do Ensino Fundamental (6 anos) poder\u00e3o optar por turmas com dois professores titulares &#8211; um deles se comunicar\u00e1 em L\u00edngua Inglesa &#8211; em formato in\u00e9dito na regi\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na modalidade bil\u00edngue, estudantes ter\u00e3o a mesma grade curricular &#8211; Ci\u00eancias Naturais e Ci\u00eancias Humanas, Matem\u00e1tica, Portugu\u00eas, Religi\u00e3o (\u00c9tica) e Artes\u00a0 &#8211; por\u00e9m, dois docentes repassar\u00e3o simultaneamente os conte\u00fados, nas l\u00ednguas Portuguesa e Inglesa. O Diretor da Institui\u00e7\u00e3o, Edson Wieth\u00f6lter, comenta que \u00e9 um projeto que vem para transformar o Vale do Taquari e levar a atual gera\u00e7\u00e3o a um novo n\u00edvel de forma\u00e7\u00e3o. \u201c\u00c9 a amplia\u00e7\u00e3o de um projeto curricular no qual acreditamos. N\u00e3o se discute mais a import\u00e2ncia da L\u00edngua Inglesa. Ela precisa habitar o dia a dia do nosso col\u00e9gio\u201d, explica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O professor respons\u00e1vel pelo Projeto Bil\u00edngue do GA, Jairo Goetz, complementa que \u201cos professores titulares estar\u00e3o em total sintonia para que os estudantes consultem ambos os docentes. V\u00e3o ter disciplinas com foco maior numa l\u00edngua, mas a outra estar\u00e1 contribuindo tamb\u00e9m, para que o estudante vivencie e se habitue aos dois idiomas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A proposta que se inicia no \u00faltimo ano da Educa\u00e7\u00e3o Infantil e 1\u00ba ano do Fundamental levar\u00e1 o estudante ao Ensino M\u00e9dio com a profici\u00eancia em n\u00edvel B1, que \u00e9 intermedi\u00e1rio, no qual a pessoa compreende e consegue reproduzir discursos de assuntos que lhe s\u00e3o familiares.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O Diretor Edson revela que cerca de cinco escolas com modalidade bil\u00edngue foram visitadas no Rio Grande do Sul e em S\u00e3o Paulo na elabora\u00e7\u00e3o do projeto, para que se expandisse o olhar sobre essa modalidade de ensino. \u201cAp\u00f3s acolher expertise de todas as escolas, inclinamos pela proposta da escola paulista, que adota a dupla doc\u00eancia. N\u00e3o temos conhecimento de nenhuma institui\u00e7\u00e3o com um projeto assim como o nosso no estado, se valendo da dupla doc\u00eancia, al\u00e9m de estarmos protagonizando essa modalidade de educa\u00e7\u00e3o no Vale\u201d, explica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A coordenadora da \u00c1rea de Linguagens e da Educa\u00e7\u00e3o Infantil e Anos Iniciais do GA, Deliene Kotz, ressalta a import\u00e2ncia de expandir o curr\u00edculo atual do col\u00e9gio, baseado na \u00eanfase em l\u00edngua adicional, para o bil\u00edngue. \u201cA Neuroci\u00eancia nos mostra o quanto que o aprendizado de uma segunda l\u00edngua contribui para nosso desenvolvimento e que esta aquisi\u00e7\u00e3o pode iniciar desde muito cedo. A plasticidade cerebral far\u00e1 com que a crian\u00e7a realize as devidas rela\u00e7\u00f5es de quando ela usar\u00e1 cada l\u00edngua. A gente est\u00e1 falando de um mundo de oportunidades que se abre pra essa crian\u00e7a\u201d, comenta.<\/span><\/p>\n<p><b>Resultados projetados<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A avalia\u00e7\u00e3o da profici\u00eancia dos estudantes inicia no 4\u00ba ano do Ensino Fundamental, quando os alunos devem atingir o n\u00edvel A1 da <\/span><i><span style=\"font-weight: 400;\">Cambridge English Language Assessment. <\/span><\/i><span style=\"font-weight: 400;\">At\u00e9 o t\u00e9rmino do 6\u00ba ano do Ensino Fundamental, os estudantes devem chegar ao n\u00edvel A2 e na conclus\u00e3o do 9\u00ba ano do Ensino Fundamental, espera-se que os discentes atinjam o n\u00edvel B1. J\u00e1 no Ensino M\u00e9dio, a expectativa \u00e9 de conquistar o B2.<\/span><\/p>\n<p><b>Matr\u00edculas<\/b><\/p>\n<p><span style=\"font-weight: 400;\">As matr\u00edculas para as turmas bil\u00edngues de 2022, para N\u00edvel III e 1\u00ba ano do Ensino Fundamental, est\u00e3o abertas na secretaria do col\u00e9gio. Mais informa\u00e7\u00f5es podem ser obtidas pelo telefone (51) 3714 3214.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Col\u00e9gio Sinodal Gustavo Adolfo lan\u00e7a, na manh\u00e3 desta quarta-feira (01), dois projetos in\u00e9ditos na regi\u00e3o &#8211; um deles em parceria com a Universidade do Vale do Taquari (Univates). Autoridades, estudantes de 9\u00ba ano e imprensa prestigiam a apresenta\u00e7\u00e3o das novidades no Teatro Univates. O p\u00fablico em geral acompanha as explana\u00e7\u00f5es pelos canais digitais das<br \/><a class=\"moretag\" href=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/2021\/09\/01\/gustavo-adolfo-tera-parceria-com-a-univates-no-ensino-medio-e-turmas-bilingues-a-partir-de-2022\/\">+ Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1435"}],"collection":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/comments?post=1435"}],"version-history":[{"count":2,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1435\/revisions"}],"predecessor-version":[{"id":1439,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1435\/revisions\/1439"}],"wp:attachment":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media?parent=1435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/categories?post=1435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/tags?post=1435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}