{"id":1309,"date":"2021-07-03T09:54:25","date_gmt":"2021-07-03T12:54:25","guid":{"rendered":"https:\/\/gustavoadolfo.com.br\/portal\/?p=1309"},"modified":"2021-06-30T16:56:33","modified_gmt":"2021-06-30T19:56:33","slug":"estudantes-contarao-com-oficinas-e-bate-papos-no-festival-do-livro","status":"publish","type":"post","link":"https:\/\/gustavoadolfo.com.br\/saocristovao\/2021\/07\/03\/estudantes-contarao-com-oficinas-e-bate-papos-no-festival-do-livro\/","title":{"rendered":"Estudantes contar\u00e3o com oficinas e bate-papos no Festival do Livro"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Estudantes do GA participar\u00e3o de oficinas e bate-papos com escritores e pesquisadores durante o 19\u00ba Festival do Livro do Col\u00e9gio Sinodal Gustavo Adolfo. As atra\u00e7\u00f5es que ser\u00e3o exclusivas para determinadas turmas levam em considera\u00e7\u00e3o os conte\u00fados de estudo de cada n\u00edvel de ensino e servem de experi\u00eancia na intera\u00e7\u00e3o com os convidados.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O festival ocorre de 5 a 16 de julho, com atra\u00e7\u00f5es h\u00edbridas para estudantes e on-line para a comunidade em geral. Pelo site do col\u00e9gio, voc\u00ea confere a programa\u00e7\u00e3o completa com as atra\u00e7\u00f5es abertas ao p\u00fablico. Na segunda semana do evento ser\u00e3o realizadas apresenta\u00e7\u00f5es de alunos.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><b>Confira as atividades exclusivas para determinadas turmas:<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">05\/07, \u00e0s 9h &#8211; Bate-papo com Ana Cec\u00edlia Togni e representa\u00e7\u00e3o do seu livro\u00a0 &#8211; 9\u00ba ano do Ensino Fundamental e 1\u00ba ano do Ensino M\u00e9dio<\/span><\/p>\n<p><span style=\"font-weight: 400;\">06\/07 &#8211; Oficina &#8211; Escrita Criativa com Gisele Gama &#8211;\u00a0 6\u00ba e 7\u00ba anos, das 14h \u00e0s 15h\u00a0 e 8\u00ba e 9\u00ba anos, das 15h30 \u00e0s 16h30<\/span><\/p>\n<p><span style=\"font-weight: 400;\">07\/07, \u00e0s 10h30min &#8211; Oficina &#8211; Escrita Criativa, com Rosiene Haetinger &#8211; Ensino M\u00e9dio<\/span><\/p>\n<p><span style=\"font-weight: 400;\">08\/07, \u00e0s 9h &#8211; Bate-papo com C\u00e9sar Obeid &#8211; 8\u00ba ano<\/span><\/p>\n<p><span style=\"font-weight: 400;\">08\/07, \u00e0s 9h &#8211; Bate-papo com \u00c1lvaro Santi &#8211; 1\u00ba e 2\u00ba Ano\/EM\u00a0 sobre o processo de escrita do texto e da poesia<\/span><\/p>\n<p><span style=\"font-weight: 400;\">08\/07, \u00e0s 9h &#8211; Bate-papo com Katharina Weitzmann &#8211; Literatura Irm\u00e3os Grimm &#8211; 6\u00ba ano<\/span><\/p>\n<p><span style=\"font-weight: 400;\">09\/07, \u00e0s 9h &#8211; Bate-papo com Telma Guimar\u00e3es &#8211; 7\u00ba anos<\/span><\/p>\n<p><span style=\"font-weight: 400;\">09\/07 &#8211; Bate-papo Comunica\u00e7\u00e3o N\u00e3o-Violenta e Cultura de Paz, com T\u00e2nia Frohlich Rodrigues &#8211; 3\u00ba ano A do EM, das 08h15min \u00e0s 9h05min; 3\u00ba ano B do EM, das 9h05min \u00e0s 9h55min<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudantes do GA participar\u00e3o de oficinas e bate-papos com escritores e pesquisadores durante o 19\u00ba Festival do Livro do Col\u00e9gio Sinodal Gustavo Adolfo. As atra\u00e7\u00f5es que ser\u00e3o exclusivas para determinadas turmas levam em considera\u00e7\u00e3o os conte\u00fados de estudo de cada n\u00edvel de ensino e servem de experi\u00eancia na intera\u00e7\u00e3o com os convidados. &nbsp; O festival<br \/><a class=\"moretag\" href=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/2021\/07\/03\/estudantes-contarao-com-oficinas-e-bate-papos-no-festival-do-livro\/\">+ Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1309"}],"collection":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/comments?post=1309"}],"version-history":[{"count":1,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1309\/revisions"}],"predecessor-version":[{"id":1310,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1309\/revisions\/1310"}],"wp:attachment":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media?parent=1309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/categories?post=1309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/tags?post=1309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}