{"id":1236,"date":"2021-05-03T17:11:55","date_gmt":"2021-05-03T20:11:55","guid":{"rendered":"https:\/\/gustavoadolfo.com.br\/portal\/?p=1236"},"modified":"2021-05-03T17:12:38","modified_gmt":"2021-05-03T20:12:38","slug":"1236","status":"publish","type":"post","link":"https:\/\/gustavoadolfo.com.br\/saocristovao\/2021\/05\/03\/1236\/","title":{"rendered":"Estudantes de 9\u00ba a Ensino M\u00e9dio t\u00eam retorno \u00e0s aulas na Univates"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-1237\" src=\"https:\/\/gustavoadolfo.com.br\/portal\/wp-content\/uploads\/2021\/05\/8-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/05\/8-300x300.png 300w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/05\/8-150x150.png 150w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/05\/8-768x768.png 768w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2021\/05\/8.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Estudantes de 9\u00ba ano do Ensino Fundamental a 3\u00ba ano do Ensino M\u00e9dio tiveram uma volta \u00e0s aulas diferente nesta segunda-feira (03).<\/p>\n<div><\/div>\n<div>Os alunos retornaram \u00e0s atividades presenciais e, para estarem em sua totalidade, est\u00e3o ocupando as instala\u00e7\u00f5es da Universidade do Vale do Taquari (Univates).<\/div>\n<div><\/div>\n<div>As oito turmas de estudantes foram acomodadas no pr\u00e9dio 7. A mudan\u00e7a que deve valer at\u00e9 o fim do ano garantiu que todos os estudantes pudessem estar em aulas presenciais a partir de hoje (03).<\/div>\n<div><\/div>\n<div>Alunos de 6\u00ba a 8\u00ba do Ensino Fundamental tamb\u00e9m voltaram ao formato presencial nesta segunda. Os estudantes de Educa\u00e7\u00e3o Infantil e Anos Iniciais do Ensino Fundamental j\u00e1 haviam retomado as aulas no col\u00e9gio na semana passada.<\/div>\n<div><\/div>\n<div>Confira alguns registros!<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estudantes de 9\u00ba ano do Ensino Fundamental a 3\u00ba ano do Ensino M\u00e9dio tiveram uma volta \u00e0s aulas diferente nesta segunda-feira (03). Os alunos retornaram \u00e0s atividades presenciais e, para estarem em sua totalidade, est\u00e3o ocupando as instala\u00e7\u00f5es da Universidade do Vale do Taquari (Univates). As oito turmas de estudantes foram acomodadas no pr\u00e9dio 7.<br \/><a class=\"moretag\" href=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/2021\/05\/03\/1236\/\">+ Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":1237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1236"}],"collection":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/comments?post=1236"}],"version-history":[{"count":2,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1236\/revisions"}],"predecessor-version":[{"id":1239,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1236\/revisions\/1239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media\/1237"}],"wp:attachment":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media?parent=1236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/categories?post=1236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/tags?post=1236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}