{"id":1013,"date":"2020-07-20T13:47:32","date_gmt":"2020-07-20T16:47:32","guid":{"rendered":"http:\/\/gustavoadolfo.com.br\/portal\/?p=1013"},"modified":"2020-07-20T13:47:32","modified_gmt":"2020-07-20T16:47:32","slug":"estudantes-do-colegio-sinodal-gustavo-adolfo-participam-de-conversa-internacional-sobre-racismo","status":"publish","type":"post","link":"https:\/\/gustavoadolfo.com.br\/saocristovao\/2020\/07\/20\/estudantes-do-colegio-sinodal-gustavo-adolfo-participam-de-conversa-internacional-sobre-racismo\/","title":{"rendered":"Estudantes do Col\u00e9gio Sinodal Gustavo Adolfo participam de conversa internacional sobre racismo"},"content":{"rendered":"<div><i>Em ingl\u00eas, alunos do Ensino M\u00e9dio tiveram videoconfer\u00eancia com norteamericana integrante de movimentos sociais.<br \/>\n<\/i><br \/>\nTendo em vista a import\u00e2ncia de se discutir temas atuais e emergentes da sociedade no ambiente escolar, o Col\u00e9gio Sinodal Gustavo Adolfo promoveu uma atividade diferente, em ingl\u00eas, voltada aos estudantes dos 2\u00ba e 3\u00ba anos do Ensino M\u00e9dio na \u00faltima semana. Eles participaram de uma videoconfer\u00eancia a fim de debater conte\u00fados envolvendo racismo nos Estados Unidos da Am\u00e9rica, com a media\u00e7\u00e3o da professora aposentada da faculdade luterana Wartburg College e integrante de movimentos sociais, Bonita Bock. A a\u00e7\u00e3o foi promovida nas disciplinas de Sociologia e L\u00edngua Inglesa. O di\u00e1logo ocorreu totalmente em ingl\u00eas.<\/p>\n<p>A respeito dos fatos que foram registrados nos \u00faltimos tempos relacionados ao racismo nos EUA, Bonita declarou, durante a conversa, que \u201cn\u00e3o \u00e9 um problema individual. Ou seja, mesmo que eu como cidad\u00e3 trabalhe contra atitudes racistas, n\u00e3o significa que n\u00e3o fa\u00e7o parte desse sistema\u201d. Ela afirma que as m\u00eddias sociais ajudam a ver o que acontece, assim as pessoas n\u00e3o descartam mais tanto o tema do preconceito racial. \u201cFinalmente, as pessoas n\u00e3o podem mais dizer que isso n\u00e3o acontece nos EUA. Temos tido protestos por semanas\u201d, explica Bonita.<\/p>\n<p>Para a estudante B\u00e1rbara Mallmann, do 2\u00ba ano B, chamou a aten\u00e7\u00e3o a fala de Bonita sobre protestos antirracismo. \u201cMesmo com acesso \u00e0s informa\u00e7\u00f5es divulgadas pela m\u00eddia, ouvir o depoimento de algu\u00e9m da realidade em quest\u00e3o \u00e9 essencial para entender, sem influ\u00eancia de marketing, o que realmente acontece e como os cidad\u00e3os t\u00eam agido a partir disso. A troca de ideias com pessoas afastadas da nossa realidade, sem necessariamente ser de fora do Brasil, \u00e9 um passo importante para o entendimento do mundo como um todo\u201d, completa.<\/p>\n<p>Nikolas Goetz \u00e9 do 3\u00ba ano do Ensino M\u00e9dio e concorda com B\u00e1rbara. \u201cA vis\u00e3o interna da situa\u00e7\u00e3o do racismo estrutural nos EUA deu uma perspectiva diferente de mundo.\u00a0 Evidenciou como todos podem perpetuar a luta contra esse preconceito e difundir a problem\u00e1tica na sociedade, muitas vezes por meio de a\u00e7\u00f5es involunt\u00e1rias atreladas \u00e0s viv\u00eancias de uma sociedade racista\u201d, esclarece. Segundo ele, \u00e9 muito comum que indiv\u00edduos como negros, asi\u00e1ticos e latinos sejam tratados de modo diferente pela pol\u00edcia e sistema jur\u00eddico do que os brancos, por exemplo. \u201cIsso est\u00e1 sendo contestado por manifesta\u00e7\u00f5es, principalmente pelo movimento Black Lives Matter\u201d, informa.<\/p>\n<p>Na opini\u00e3o de Goetz, a atividade ajudou a perceber as influ\u00eancias causadas pelo que acontece no norte do continente americano, aqui no Brasil. \u201cSomos privilegiados e o ideal \u00e9 tirarmos proveito disso para, ao inv\u00e9s de praticar ainda mais a segrega\u00e7\u00e3o, construir uma sociedade mais justa. Agir do local para o global\u201d, reconhece. Ele acrescenta dizendo que \u201ccomo brancos, devemos dar lugar \u00e0 fala de minorias que se encontram sufocadas h\u00e1 anos pela sociedade. Temos que mudar essa postura racista, uma vez que o preconceito se encontra enraizado na sociedade brasileira\u201d, finaliza.<\/p>\n<p>A estudante Ana Carolina R\u00f6shig do 2\u00ba ano A do Ensino M\u00e9dio defende a fala de Bonita quando ela encoraja a seguir os sonhos e lutar pelo que se acredita. \u201cAfinal, n\u00f3s somos o futuro e as pr\u00f3ximas lideran\u00e7as do planeta. Foi incr\u00edvel, pois pude ter uma vis\u00e3o geral de algo que conhecia, mas n\u00e3o tinha repert\u00f3rio para dialogar sobre\u201d, comenta.<\/p>\n<p>Na a\u00e7\u00e3o, a professora de Sociologia Ana Cristina Kircheim e as docentes de L\u00edngua Inglesa Gilm\u00e1rcia Picoli e Melissa Sell conseguiram unir cultura, discuss\u00e3o de temas sociais e aprendizagem de idioma de forma enriquecedora para todos em muitos aspectos. Melissa afirma que o resultado da atividade foi positivo, pois os estudantes participaram com perguntas pertinentes. \u201cEles puderam conhecer mais sobre o trabalho volunt\u00e1rio e projetos sociais desenvolvidos por Bonita. Com certeza foram momentos de muita aprendizagem e desenvolvimento da l\u00edngua bem como consci\u00eancia social\u201d, finaliza.<\/p>\n<p><b>Pr\u00e1tica da L\u00edngua Inglesa<br \/>\n<\/b><br \/>\nPara a estudante B\u00e1rbara, falar em ingl\u00eas com algu\u00e9m que n\u00e3o mora no Brasil \u00e9 importante para exercitar o idioma. \u201c\u00c9 um desafio e ao mesmo tempo gratificante se \u2018fazer entender\u2019 para um estrangeiro em sua l\u00edngua natal\u201d, conta. Conforme a professora Gilm\u00e1rcia, &#8220;al\u00e9m de ter sido uma experi\u00eancia real de fala da L\u00edngua Inglesa, foi uma oportunidade que abriu caminhos para outras futuras&#8221;. O Col\u00e9gio Sinodal Gustavo Adolfo conta com \u00eanfase em l\u00edngua estrangeira, possibilitando experi\u00eancias internacionais nas l\u00ednguas inglesa e alem\u00e3.<\/div>\n<div><\/div>\n<div><img loading=\"lazy\" class=\"alignnone size-medium wp-image-1014\" src=\"http:\/\/gustavoadolfo.com.br\/portal\/wp-content\/uploads\/2020\/07\/Videoconfer\u00eancia-bonita_3-300x123.jpeg\" alt=\"\" width=\"300\" height=\"123\" srcset=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2020\/07\/Videoconfer\u00eancia-bonita_3-300x123.jpeg 300w, https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-content\/uploads\/2020\/07\/Videoconfer\u00eancia-bonita_3.jpeg 560w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em ingl\u00eas, alunos do Ensino M\u00e9dio tiveram videoconfer\u00eancia com norteamericana integrante de movimentos sociais. Tendo em vista a import\u00e2ncia de se discutir temas atuais e emergentes da sociedade no ambiente escolar, o Col\u00e9gio Sinodal Gustavo Adolfo promoveu uma atividade diferente, em ingl\u00eas, voltada aos estudantes dos 2\u00ba e 3\u00ba anos do Ensino M\u00e9dio na \u00faltima<br \/><a class=\"moretag\" href=\"https:\/\/gustavoadolfo.com.br\/saocristovao\/2020\/07\/20\/estudantes-do-colegio-sinodal-gustavo-adolfo-participam-de-conversa-internacional-sobre-racismo\/\">+ Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":1014,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1013"}],"collection":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/comments?post=1013"}],"version-history":[{"count":1,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1013\/revisions"}],"predecessor-version":[{"id":1015,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/posts\/1013\/revisions\/1015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media\/1014"}],"wp:attachment":[{"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/media?parent=1013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/categories?post=1013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gustavoadolfo.com.br\/saocristovao\/wp-json\/wp\/v2\/tags?post=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}